{"id":2075,"date":"2024-02-19T14:03:53","date_gmt":"2024-02-19T13:03:53","guid":{"rendered":"https:\/\/transformadosmetalicostoral.com\/?p=2075"},"modified":"2024-02-19T14:03:55","modified_gmt":"2024-02-19T13:03:55","slug":"coupage-au-plasma","status":"publish","type":"post","link":"https:\/\/transformadosmetalicostoral.com\/fr\/corte-por-plasma\/","title":{"rendered":"Qu\u2019est-ce que le coupage plasma et quand est-il utilis\u00e9 ?"},"content":{"rendered":"<p>Dans le monde de <strong>m\u00e9canis\u00e9<\/strong>, la pr\u00e9cision est la cl\u00e9. Dans l&#039;industrie <strong>travail des m\u00e9taux<\/strong>, la pr\u00e9cision est essentielle pour <strong>fabrication de pi\u00e8ces de qualit\u00e9<\/strong>. L&#039;une des technologies les plus r\u00e9volutionnaires est <strong>coupage au plasma<\/strong> et, chez Transformados Met\u00e1licos Toral, nous sommes <a href=\"https:\/\/transformadosmetalicostoral.com\/fr\/machinerie\/\" target=\"_blank\" rel=\"noreferrer noopener\">experts en machines<\/a> pour la r\u00e9alisation de pi\u00e8ces simples ou tr\u00e8s complexes. Le d\u00e9coupage plasma ne fait pas exception. En quoi consiste cette technique ? Quand est-il utilis\u00e9 ? <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu\u2019est-ce que le coupage plasma ?<\/h2>\n\n\n\n<p>Le coupage plasma est une technique de coupage qui utilise un <strong>jet de plasma<\/strong> hautement ionis\u00e9 pour la coupe <strong>m\u00e9taux conducteurs<\/strong>. En termes plus simples, imaginez un jet de plasma, ce quatri\u00e8me \u00e9tat de la mati\u00e8re o\u00f9 <strong>\u00e9lectrons <\/strong>et les <strong>ions <\/strong>Ils cohabitent en parfait \u00e9quilibre, \u00e9nergiques et contr\u00f4l\u00e9s. Eh bien, le jet est dirig\u00e9 pr\u00e9cis\u00e9ment \u00e0 travers le <strong>mati\u00e8re \u00e0 couper<\/strong>, cr\u00e9ant une s\u00e9paration nette avec des bords bien d\u00e9finis.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2024\/02\/plasma.jpg\" alt=\"Il existe aujourd&#039;hui des machines de d\u00e9coupe plasma CNC\" class=\"wp-image-2077\" srcset=\"https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2024\/02\/plasma.jpg 1000w, https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2024\/02\/plasma-300x200.jpg 300w, https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2024\/02\/plasma-768x512.jpg 768w, https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2024\/02\/plasma-18x12.jpg 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p>En termes plus techniques, le <strong>coupage au plasma<\/strong> Il a un principe de fonctionnement dans lequel la temp\u00e9rature du mat\u00e9riau est \u00e9lev\u00e9e localement, au-dessus de la<strong> 20 000 degr\u00e9s Celsius<\/strong>. De cette fa\u00e7on, le gaz utilis\u00e9 est achemin\u00e9 vers le <strong>quatri\u00e8me \u00e9tat de la mati\u00e8re<\/strong> (plasma) et quel est l&#039;\u00e9tat dans lequel le <strong>\u00e9lectrons <\/strong>ils se dissocient de <strong>atome<\/strong>, tandis que le gaz <strong>ionise<\/strong>. Cette technique n\u00e9cessite des machines sp\u00e9ciales, ainsi qu&#039;un op\u00e9rateur expert.<\/p>\n\n\n\n<p>Pour le coupage au plasma, un <strong>g\u00e9n\u00e9rateur haute fr\u00e9quence<\/strong> qui fonctionne avec de l&#039;\u00e9nergie \u00e9lectrique ; De plus, il est utilis\u00e9 <strong>gaz <\/strong>pour g\u00e9n\u00e9rer la flamme chauffante et qui sera ensuite ionis\u00e9e. Parmi les gaz utilis\u00e9s on retrouve <strong>argon<\/strong>, <strong>hydrog\u00e8ne <\/strong>et <strong>azote<\/strong>. D&#039;autre part, le d\u00e9coupeur plasma, comme on l&#039;appelle, utilise un <strong>\u00e9lectrode <\/strong>et un <strong>porte-\u00e9lectrode<\/strong>; Ceux-ci, selon le gaz, peuvent \u00eatre en zirconium, tungst\u00e8ne ou hafnium. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quand utilise-t-on le d\u00e9coupage plasma ?<\/h2>\n\n\n\n<p>L\u2019un des avantages du coupage plasma est qu\u2019il peut \u00eatre appliqu\u00e9 \u00e0 une grande vari\u00e9t\u00e9 de travaux. La d\u00e9coupe elle-m\u00eame est tr\u00e8s polyvalente et permet de travailler sur des pi\u00e8ces complexes qui n\u00e9cessitent des tol\u00e9rances tr\u00e8s exigeantes. Cette technique est utilis\u00e9e pour :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Coupez une grande vari\u00e9t\u00e9 de <strong>m\u00e9taux conducteurs<\/strong>. Ils comprennent l&#039;acier inoxydable, l&#039;aluminium, l&#039;acier au carbone et le cuivre. Quelle que soit la duret\u00e9 ou la composition du m\u00e9tal, la d\u00e9coupe au plasma peut le couper avec facilit\u00e9 et pr\u00e9cision.<\/li>\n\n\n\n<li>Pour <strong>travail de pr\u00e9cision et de rapidit\u00e9<\/strong>. Avez-vous besoin de coupes nettes et rapides ? Le d\u00e9coupage plasma est une excellente alternative. Sa capacit\u00e9 \u00e0 couper avec une grande pr\u00e9cision et une grande vitesse en fait le choix privil\u00e9gi\u00e9 dans les applications o\u00f9 le <strong>temps <\/strong>et la <strong>qualit\u00e9 <\/strong>Ils sont fondamentaux.<\/li>\n\n\n\n<li><strong>coupes complexes<\/strong>. Si la pi\u00e8ce n\u00e9cessite des coupes complexes ou des formes compliqu\u00e9es, le coupage plasma est connu pour sa capacit\u00e9 \u00e0 r\u00e9aliser <strong>coupes courbes et angulaires<\/strong> facilement. Cette technique est utilis\u00e9e pour la fabrication de pi\u00e8ces de machines et m\u00eame pour des travaux de bricolage. <\/li>\n\n\n\n<li><strong>Pour \u00e9paisseurs variables<\/strong>. Contrairement \u00e0 d\u2019autres techniques de d\u00e9coupe, la d\u00e9coupe plasma n\u2019est pas g\u00ean\u00e9e par les variations d\u2019\u00e9paisseur. Avec ce type d&#039;usinage, il est possible de travailler des t\u00f4les fines jusqu&#039;\u00e0 <strong>plaques \u00e9paisses<\/strong>, puisque la d\u00e9coupe plasma peut s&#039;adapter \u00e0 une large gamme d&#039;\u00e9paisseurs de mat\u00e9riaux sans compromettre la qualit\u00e9 de la d\u00e9coupe.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Les avantages de l\u2019usinage plasma<\/h2>\n\n\n\n<p>Nous avons d\u00e9j\u00e0 vu dans quels cas cela est utilis\u00e9 <strong>technique<\/strong>, Et quels sont les avantages ? Si nous sommes plus pr\u00e9cis, nous constatons que <strong>coupeur de plasma <\/strong>offre moins de d\u00e9formation thermique. Contrairement \u00e0 d&#039;autres techniques, comme <strong>d\u00e9coupe au laser<\/strong> ou la coupe par <strong>appelle<\/strong>, le plasma g\u00e9n\u00e8re<strong> moins de chaleur<\/strong> dans la zone affect\u00e9e, ce qui entra\u00eene moins de d\u00e9formation thermique du mat\u00e9riau. <\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2024\/02\/cortadora.jpg\" alt=\"Les \u00e9lectrodes et les buses sont utilis\u00e9es dans le coupage plasma.\" class=\"wp-image-2078\" srcset=\"https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2024\/02\/cortadora.jpg 1000w, https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2024\/02\/cortadora-300x200.jpg 300w, https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2024\/02\/cortadora-768x512.jpg 768w, https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2024\/02\/cortadora-18x12.jpg 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p>En revanche, les \u00e9quipes sont assez <strong>moderne <\/strong>et offrent la possibilit\u00e9 d&#039;ajuster une vari\u00e9t\u00e9 de param\u00e8tres. Les cutters permettent de moduler le <strong>actuel<\/strong>, il <strong>flux du gaz<\/strong> et la <strong>vitesse de coupe<\/strong>; De cette mani\u00e8re, les machines s&#039;adaptent aux besoins de chaque travail. Les r\u00e9sultats sont donc optimaux et de grande qualit\u00e9.<\/p>\n\n\n\n<p>Bien que le coupage au plasma implique l&#039;utilisation de <strong>hautes temp\u00e9ratures<\/strong> et <strong>flux \u00e9lectrique<\/strong>, les machines sont con\u00e7ues avec des caract\u00e9ristiques de <strong>s\u00e9curit\u00e9 <\/strong>avanc\u00e9 pour prot\u00e9ger \u00e0 la fois l\u2019op\u00e9rateur et l\u2019environnement de travail. Des syst\u00e8mes de d\u00e9tection d&#039;arc aux dispositifs de protection contre la surchauffe, la s\u00e9curit\u00e9 est une priorit\u00e9 \u00e0 chaque \u00e9tape du processus. Bien entendu, il est n\u00e9cessaire que l&#039;usinage soit r\u00e9alis\u00e9 par un <strong>op\u00e9rateur qualifi\u00e9<\/strong>.<\/p>\n\n\n\n<p>Il convient de noter que, si on le compare avec d&#039;autres <strong>formes de d\u00e9coupe<\/strong>, le plasma est beaucoup moins cher en termes de co\u00fbt d&#039;exploitation. Articles consommables, tels que <strong>\u00e9lectrodes <\/strong>et les <strong>buses<\/strong>, sont relativement abordables et l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique du processus contribue \u00e0 r\u00e9duire les co\u00fbts \u00e9nerg\u00e9tiques \u00e0 long terme. Nous ne pouvons conclure cet article sans mentionner qu\u2019il existe aujourd\u2019hui <strong>coupeurs de plasma<\/strong> <a href=\"https:\/\/transformadosmetalicostoral.com\/fr\/avantages-des-machines-cnc-pour-lindustrie\/\" target=\"_blank\" rel=\"noreferrer noopener\">CNC<\/a> ce qui rend l&#039;usinage beaucoup plus facile.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le coupage plasma est un type d&#039;usinage qui utilise un gaz ionis\u00e9 pour d\u00e9couper une pi\u00e8ce afin d&#039;obtenir une finition pr\u00e9cise.<\/p>","protected":false},"author":7,"featured_media":2079,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[64],"tags":[98,91,86,85,77],"class_list":["post-2075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-corte-por-plasma","tag-maquinas-herramienta","tag-mecanizados","tag-metales","tag-transformados-metalicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 es el corte por plasma y cu\u00e1ndo se utiliza?<\/title>\n<meta name=\"description\" content=\"El corte por plasma es un tipo de mecanizado en el que se utiliza un gas ionizado para cortar una pieza y lograr un acabado preciso\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transformadosmetalicostoral.com\/fr\/coupage-au-plasma\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es el corte por plasma y cu\u00e1ndo se utiliza?\" \/>\n<meta property=\"og:description\" content=\"El corte por plasma es un tipo de mecanizado en el que se utiliza un gas ionizado para cortar una pieza y lograr un acabado preciso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transformadosmetalicostoral.com\/fr\/coupage-au-plasma\/\" \/>\n<meta property=\"og:site_name\" content=\"Transformados Met\u00e1licos Toral\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Transformados-Metalicos-Toral-100046589936217\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-19T13:03:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-19T13:03:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2024\/02\/cortadora-plasma-e1708347611278.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carolina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carolina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/corte-por-plasma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/corte-por-plasma\\\/\"},\"author\":{\"name\":\"Carolina\",\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/#\\\/schema\\\/person\\\/b9007ef85d76e5297b75c0bbfb645c8e\"},\"headline\":\"\u00bfQu\u00e9 es el corte por plasma y cu\u00e1ndo se utiliza?\",\"datePublished\":\"2024-02-19T13:03:53+00:00\",\"dateModified\":\"2024-02-19T13:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/corte-por-plasma\\\/\"},\"wordCount\":882,\"publisher\":{\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/corte-por-plasma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cortadora-plasma-e1708347611278.jpg\",\"keywords\":[\"corte por plasma\",\"m\u00e1quinas herramienta\",\"mecanizados\",\"metales\",\"transformados met\u00e1licos\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/corte-por-plasma\\\/\",\"url\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/corte-por-plasma\\\/\",\"name\":\"\u00bfQu\u00e9 es el corte por plasma y cu\u00e1ndo se utiliza?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/corte-por-plasma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/corte-por-plasma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cortadora-plasma-e1708347611278.jpg\",\"datePublished\":\"2024-02-19T13:03:53+00:00\",\"dateModified\":\"2024-02-19T13:03:55+00:00\",\"description\":\"El corte por plasma es un tipo de mecanizado en el que se utiliza un gas ionizado para cortar una pieza y lograr un acabado preciso\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/corte-por-plasma\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transformadosmetalicostoral.com\\\/corte-por-plasma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/corte-por-plasma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cortadora-plasma-e1708347611278.jpg\",\"contentUrl\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cortadora-plasma-e1708347611278.jpg\",\"width\":1200,\"height\":800,\"caption\":\"El corte por plasma es una t\u00e9cnica que eleva un gas al cuarto estado de la materia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/corte-por-plasma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es el corte por plasma y cu\u00e1ndo se utiliza?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/#website\",\"url\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/\",\"name\":\"Transformados met\u00e1licos Toral\",\"description\":\"Trabajos de estampaci\u00f3n y\u00a0embutici\u00f3n de piezas met\u00e1licas, soldadura de acero, aluminio y acero inoxidable, y en el dise\u00f1o, construcci\u00f3n\u00a0y montaje de instalaciones mec\u00e1nicas llave en mano\",\"publisher\":{\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/#organization\"},\"alternateName\":\"Transformados met\u00e1licos Toral\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/#organization\",\"name\":\"Transformados met\u00e1licos Toral\",\"alternateName\":\"Transformados met\u00e1licos Toral\",\"url\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Transformados met\u00e1licos Toral\"},\"image\":{\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Transformados-Metalicos-Toral-100046589936217\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/transformados-metalicos-toral-sl\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/#\\\/schema\\\/person\\\/b9007ef85d76e5297b75c0bbfb645c8e\",\"name\":\"Carolina\",\"url\":\"https:\\\/\\\/transformadosmetalicostoral.com\\\/fr\\\/author\\\/carolinah\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u2019est-ce que le coupage plasma et quand est-il utilis\u00e9 ?","description":"Le coupage plasma est un type d&#039;usinage qui utilise un gaz ionis\u00e9 pour d\u00e9couper une pi\u00e8ce afin d&#039;obtenir une finition pr\u00e9cise.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transformadosmetalicostoral.com\/fr\/coupage-au-plasma\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00bfQu\u00e9 es el corte por plasma y cu\u00e1ndo se utiliza?","og_description":"El corte por plasma es un tipo de mecanizado en el que se utiliza un gas ionizado para cortar una pieza y lograr un acabado preciso","og_url":"https:\/\/transformadosmetalicostoral.com\/fr\/coupage-au-plasma\/","og_site_name":"Transformados Met\u00e1licos Toral","article_publisher":"https:\/\/www.facebook.com\/p\/Transformados-Metalicos-Toral-100046589936217\/","article_published_time":"2024-02-19T13:03:53+00:00","article_modified_time":"2024-02-19T13:03:55+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2024\/02\/cortadora-plasma-e1708347611278.jpg","type":"image\/jpeg"}],"author":"Carolina","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Carolina","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transformadosmetalicostoral.com\/corte-por-plasma\/#article","isPartOf":{"@id":"https:\/\/transformadosmetalicostoral.com\/corte-por-plasma\/"},"author":{"name":"Carolina","@id":"https:\/\/transformadosmetalicostoral.com\/#\/schema\/person\/b9007ef85d76e5297b75c0bbfb645c8e"},"headline":"\u00bfQu\u00e9 es el corte por plasma y cu\u00e1ndo se utiliza?","datePublished":"2024-02-19T13:03:53+00:00","dateModified":"2024-02-19T13:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/transformadosmetalicostoral.com\/corte-por-plasma\/"},"wordCount":882,"publisher":{"@id":"https:\/\/transformadosmetalicostoral.com\/#organization"},"image":{"@id":"https:\/\/transformadosmetalicostoral.com\/corte-por-plasma\/#primaryimage"},"thumbnailUrl":"https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2024\/02\/cortadora-plasma-e1708347611278.jpg","keywords":["corte por plasma","m\u00e1quinas herramienta","mecanizados","metales","transformados met\u00e1licos"],"articleSection":["Noticias"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/transformadosmetalicostoral.com\/corte-por-plasma\/","url":"https:\/\/transformadosmetalicostoral.com\/corte-por-plasma\/","name":"Qu\u2019est-ce que le coupage plasma et quand est-il utilis\u00e9 ?","isPartOf":{"@id":"https:\/\/transformadosmetalicostoral.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transformadosmetalicostoral.com\/corte-por-plasma\/#primaryimage"},"image":{"@id":"https:\/\/transformadosmetalicostoral.com\/corte-por-plasma\/#primaryimage"},"thumbnailUrl":"https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2024\/02\/cortadora-plasma-e1708347611278.jpg","datePublished":"2024-02-19T13:03:53+00:00","dateModified":"2024-02-19T13:03:55+00:00","description":"Le coupage plasma est un type d&#039;usinage qui utilise un gaz ionis\u00e9 pour d\u00e9couper une pi\u00e8ce afin d&#039;obtenir une finition pr\u00e9cise.","breadcrumb":{"@id":"https:\/\/transformadosmetalicostoral.com\/corte-por-plasma\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transformadosmetalicostoral.com\/corte-por-plasma\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/transformadosmetalicostoral.com\/corte-por-plasma\/#primaryimage","url":"https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2024\/02\/cortadora-plasma-e1708347611278.jpg","contentUrl":"https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2024\/02\/cortadora-plasma-e1708347611278.jpg","width":1200,"height":800,"caption":"El corte por plasma es una t\u00e9cnica que eleva un gas al cuarto estado de la materia"},{"@type":"BreadcrumbList","@id":"https:\/\/transformadosmetalicostoral.com\/corte-por-plasma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/transformadosmetalicostoral.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es el corte por plasma y cu\u00e1ndo se utiliza?"}]},{"@type":"WebSite","@id":"https:\/\/transformadosmetalicostoral.com\/#website","url":"https:\/\/transformadosmetalicostoral.com\/","name":"Transformateurs m\u00e9talliques Toral","description":"Travaux d&#039;emboutissage et d&#039;emboutissage de pi\u00e8ces m\u00e9talliques, de soudage de l&#039;acier, de l&#039;aluminium et de l&#039;acier inoxydable, ainsi que dans la conception, la construction et le montage d&#039;installations m\u00e9caniques cl\u00e9 en main.","publisher":{"@id":"https:\/\/transformadosmetalicostoral.com\/#organization"},"alternateName":"Transformados met\u00e1licos Toral","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transformadosmetalicostoral.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/transformadosmetalicostoral.com\/#organization","name":"Transformateurs m\u00e9talliques Toral","alternateName":"Transformados met\u00e1licos Toral","url":"https:\/\/transformadosmetalicostoral.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/transformadosmetalicostoral.com\/#\/schema\/logo\/image\/","url":"https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2023\/06\/favicon.png","contentUrl":"https:\/\/transformadosmetalicostoral.com\/wp-content\/uploads\/2023\/06\/favicon.png","width":512,"height":512,"caption":"Transformados met\u00e1licos Toral"},"image":{"@id":"https:\/\/transformadosmetalicostoral.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Transformados-Metalicos-Toral-100046589936217\/","https:\/\/es.linkedin.com\/company\/transformados-metalicos-toral-sl"]},{"@type":"Person","@id":"https:\/\/transformadosmetalicostoral.com\/#\/schema\/person\/b9007ef85d76e5297b75c0bbfb645c8e","name":"Caroline","url":"https:\/\/transformadosmetalicostoral.com\/fr\/author\/carolinah\/"}]}},"_links":{"self":[{"href":"https:\/\/transformadosmetalicostoral.com\/fr\/wp-json\/wp\/v2\/posts\/2075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transformadosmetalicostoral.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transformadosmetalicostoral.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transformadosmetalicostoral.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/transformadosmetalicostoral.com\/fr\/wp-json\/wp\/v2\/comments?post=2075"}],"version-history":[{"count":2,"href":"https:\/\/transformadosmetalicostoral.com\/fr\/wp-json\/wp\/v2\/posts\/2075\/revisions"}],"predecessor-version":[{"id":2080,"href":"https:\/\/transformadosmetalicostoral.com\/fr\/wp-json\/wp\/v2\/posts\/2075\/revisions\/2080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transformadosmetalicostoral.com\/fr\/wp-json\/wp\/v2\/media\/2079"}],"wp:attachment":[{"href":"https:\/\/transformadosmetalicostoral.com\/fr\/wp-json\/wp\/v2\/media?parent=2075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transformadosmetalicostoral.com\/fr\/wp-json\/wp\/v2\/categories?post=2075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transformadosmetalicostoral.com\/fr\/wp-json\/wp\/v2\/tags?post=2075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}